{"id":90,"date":"2023-08-09T18:46:00","date_gmt":"2023-08-09T17:46:00","guid":{"rendered":"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/what-are-styrenic-block-copolymers\/"},"modified":"2026-06-04T14:40:43","modified_gmt":"2026-06-04T13:40:43","slug":"styrenic-block-copolymer","status":"publish","type":"post","link":"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/styrenic-block-copolymer\/","title":{"rendered":"O que s\u00e3o copol\u00edmeros em bloco de estireno?"},"content":{"rendered":"\n<div class=\"circle_s bg_orange circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading\">O que s\u00e3o copol\u00edmeros em bloco de estireno?<\/h1>\n\n\n\n<div class=\"wp-block-group holder_author has-light-green-cyan-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-post-author\"><div class=\"wp-block-post-author__content\"><p class=\"wp-block-post-author__byline\">Author<\/p><p class=\"wp-block-post-author__name\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/author\/robin-conrad\/\" target=\"_self\">Robin Conrad<\/a><\/p><\/div><\/div>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2023-08-09T18:46:00+01:00\">9. Agosto 2023<\/time><\/div><\/div><\/div>\n\n\n\n<p class=\"col_short wp-block-paragraph\">Os copol\u00edmeros em bloco de estireno (SBCs) s\u00e3o pol\u00edmeros amplamente utilizados da fam\u00edlia dos <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/what-is-tpe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>elast\u00f4meros termopl\u00e1sticos (TPEs)<\/strong><\/a>. Os TPEs s\u00e3o materiais com elasticidade semelhante \u00e0 borracha e excelente processabilidade de um material termopl\u00e1stico.<\/p>\n\n\n\n<p class=\"col_short wp-block-paragraph\">Os SBCs s\u00e3o usados como pol\u00edmero base para compostos TPE conhecidos como TPS (Elast\u00f4meros Termopl\u00e1sticos de Estireno). Estes n\u00e3o devem ser confundidos com Amido Termopl\u00e1stico (tamb\u00e9m abreviado como TPS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em termos de estrutura molecular, os SBCs geralmente consistem em dois blocos termopl\u00e1sticos de poliestireno, que formam as extremidades, e um bloco intermedi\u00e1rio, el\u00e1stico e macio. No entanto, existem v\u00e1rias configura\u00e7\u00f5es de blocos poss\u00edveis:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Di-bloco (bloco de poliestireno \u2013 bloco elastom\u00e9rico)<\/li>\n\n\n\n<li>Tri-bloco linear (bloco de poliestireno \u2013 bloco elastom\u00e9rico \u2013 bloco de poliestireno)<\/li>\n\n\n\n<li>Diversas configura\u00e7\u00f5es ramificadas, como uma estrutura radial<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-grafic.svg\" alt=\"\" class=\"wp-image-781\"\/><figcaption class=\"wp-element-caption\">Configura\u00e7\u00f5es t\u00edpicas de blocos dos SBCs<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_beige circle_top_right\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\">Propriedades<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tabela compara as propriedades dos SBCs com as de outros tipos de TPEs.<\/p>\n<\/div>\n<\/div>\n\n\n\n\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8\" aria-describedby=\"tablepress-8-description\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Properties\/Materials<\/td><td class=\"column-2\">TPS<\/td><td class=\"column-3\">TPO<\/td><td class=\"column-4\">TPVC<\/td><td class=\"column-5\">TPU<\/td><td class=\"column-6\">TPC<\/td><td class=\"column-7\">TPA<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Shore Hardness<\/td><td class=\"column-2\">30A \u301c 70A<\/td><td class=\"column-3\">60A \u301c 95A<\/td><td class=\"column-4\">40A \u301c 70A<\/td><td class=\"column-5\">80A \u301c 80D<\/td><td class=\"column-6\">90A \u301c 70D<\/td><td class=\"column-7\">40D \u301c 65D<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Tensile strength (MPa)<\/td><td class=\"column-2\">9.8 \u301c 34.3<\/td><td class=\"column-3\">2.9 \u301c 18.6<\/td><td class=\"column-4\">9.8 \u301c 19.6<\/td><td class=\"column-5\">29.4 \u301c 49<\/td><td class=\"column-6\">25.5 \u301c 39.2<\/td><td class=\"column-7\">11.8 \u301c 34.3<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Elongation (%)<\/td><td class=\"column-2\">500 \u301c 1,200<\/td><td class=\"column-3\">200 \u301c 600<\/td><td class=\"column-4\">400 \u301c 500<\/td><td class=\"column-5\">300 \u301c 800<\/td><td class=\"column-6\">350 \u301c 450<\/td><td class=\"column-7\">200 \u301c 400<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Rebound resilience (%)<\/td><td class=\"column-2\">45 \u301c 75<\/td><td class=\"column-3\">40 \u301c 60<\/td><td class=\"column-4\">30 \u301c 70<\/td><td class=\"column-5\">30 \u301c 70<\/td><td class=\"column-6\">60 \u301c 70<\/td><td class=\"column-7\">60 \u301c 70<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Density (g\/cm\u00b3)<\/td><td class=\"column-2\">0.91 \u301c 0.95<\/td><td class=\"column-3\">0.88<\/td><td class=\"column-4\">1.2 \u301c 1.3<\/td><td class=\"column-5\">1.1 \u301c 1.25<\/td><td class=\"column-6\">1.17 \u301c 1.25<\/td><td class=\"column-7\">1.01<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Abrasion resistance<\/td><td class=\"column-2\">Fair<\/td><td class=\"column-3\">Poor<\/td><td class=\"column-4\">Fair<\/td><td class=\"column-5\">Excellent<\/td><td class=\"column-6\">Fair<\/td><td class=\"column-7\">Good<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Bending resistance at room temperature<\/td><td class=\"column-2\">Good<\/td><td class=\"column-3\">Fair<\/td><td class=\"column-4\">Good<\/td><td class=\"column-5\">Good<\/td><td class=\"column-6\">Excellent<\/td><td class=\"column-7\">Excellent<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Heat resistance<\/td><td class=\"column-2\">\u301c 80\u00b0C<\/td><td class=\"column-3\">\u301c 120\u00b0C<\/td><td class=\"column-4\">\u301c 100\u00b0C<\/td><td class=\"column-5\">\u301c 100\u00b0C<\/td><td class=\"column-6\">\u301c 140\u00b0C<\/td><td class=\"column-7\">\u301c 100\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Oil resistance<\/td><td class=\"column-2\">Poor<\/td><td class=\"column-3\">Fair<\/td><td class=\"column-4\">Good<\/td><td class=\"column-5\">Excellent<\/td><td class=\"column-6\">Excellent<\/td><td class=\"column-7\">Excellent<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Weather resistance<\/td><td class=\"column-2\">Poor - good<\/td><td class=\"column-3\">Good<\/td><td class=\"column-4\">Fair - good<\/td><td class=\"column-5\">Fair - good<\/td><td class=\"column-6\">Fair<\/td><td class=\"column-7\">Good<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Brittleness temperature<\/td><td class=\"column-2\">< -70\u00b0C<\/td><td class=\"column-3\">< -70\u00b0C<\/td><td class=\"column-4\">-50\u00b0C \u301c -30\u00b0C<\/td><td class=\"column-5\">< -70\u00b0C<\/td><td class=\"column-6\">< -70\u00b0C<\/td><td class=\"column-7\">< -70\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Applications<\/td><td class=\"column-2\">Footwear,<br \/>\nresin blends,<br \/>\nadhesives,<br \/>\nasphalt modification<\/td><td class=\"column-3\">Automotive hoses \/ tubes,<br \/>\nconsumer goods<\/td><td class=\"column-4\">Automotive,<br \/>\nelectric wires \/ cables,<br \/>\ncivil engineering \/ construction<\/td><td class=\"column-5\">Footwear,<br \/>\nindustrial goods,<br \/>\nconsumer goods,<br \/>\nmedical goods<\/td><td class=\"column-6\">Automobiles,<br \/>\nelectronics,<br \/>\nindustrial goods<\/td><td class=\"column-7\">Sporting goods,<br \/>\nindustrial goods<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<span id=\"tablepress-8-description\" class=\"tablepress-table-description tablepress-table-description-id-8\">Propriedades dos SBC em compara\u00e7\u00e3o com outros tipos de TPE | Fonte: Takemura, Y.: Nippon Gomu Kyokaishi, 83, 269-276 (2010). Parcialmente revisado.<\/span>\n<!-- #tablepress-8 from cache -->\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Propriedades mec\u00e2nicas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As caracter\u00edsticas mec\u00e2nicas fundamentais dos SBCs s\u00e3o suas <strong>propriedades el\u00e1sticas semelhantes \u00e0 borracha<\/strong> combinadas com <strong>excelente maciez<\/strong>. Isso os torna adequados para <strong>aplica\u00e7\u00f5es de toque suave<\/strong> em diversas ind\u00fastrias, como <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/sporting-goods-and-footwear\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>artigos esportivos e cal\u00e7ados<\/strong><\/a>, <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/consumer-goods\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>bens de consumo<\/strong><\/a>, <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/automotive-polymers\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>mobilidade<\/strong><\/a>, <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/electronics\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>eletr\u00f4nicos<\/strong><\/a> e no setor <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/medical-grade-tpe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>m\u00e9dico hospitalar<\/strong><\/a>. Para uma lista completa, <strong><a href=\"#applications\">veja abaixo<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para aplica\u00e7\u00f5es que exigem maior dureza e resist\u00eancia mec\u00e2nica, outros TPEs como TPUs, TPCs e TPAs, podem ser mais adequados.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_s bg_cyan circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Densidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs t\u00eam menor densidade em compara\u00e7\u00e3o com TPUs, TPAs, TPCs e TPVCs, e densidade equipar\u00e1vel com TPO e TPV.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Propriedades t\u00e9rmicas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>resist\u00eancia ao calor<\/strong> dos SBCs depende da estrutura qu\u00edmica e da temperatura de transi\u00e7\u00e3o v\u00edtrea dos blocos terminais. A temperatura m\u00e1xima de opera\u00e7\u00e3o \u00e9 de ~ 80\u00baC. A <strong>temperatura de fragilidade<\/strong> \u00e9 o ponto no qual o pol\u00edmero transita de um estado borrachoso para um estado v\u00edtreo, que \u00e9 muito mais duro e fr\u00e1gil. A baixa temperatura de fragilidade dos SBCs permite seu uso em aplica\u00e7\u00f5es de baixa temperatura que exigem boa resist\u00eancia ao impacto e flexibilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para as pontua\u00e7\u00f5es observadas, consulte a tabela acima.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Distribui\u00e7\u00e3o de peso molecular<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs t\u00eam uma distribui\u00e7\u00e3o estreita de peso molecular em compara\u00e7\u00e3o com outros TPEs, uma vez que o TPS \u00e9 produzido por polimeriza\u00e7\u00e3o ani\u00f4nica viva.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Processabilidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs podem ser <strong>moldados por inje\u00e7\u00e3o<\/strong>, <strong>extrusados<\/strong>, <strong>moldados por extrus\u00e3o e sopro<\/strong> e <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/3d-printing\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>impress\u00e3o 3D<\/strong><\/a>. Isso, juntamente com suas excelentes caracter\u00edsticas de desempenho, os torna uma excelente escolha de material para uma ampla gama de <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>aplica\u00e7\u00f5es<\/strong><\/a> em muitos setores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A capacidade de <strong>derreter e remodelar<\/strong> os SBCs permite a reciclagem e possibilita o processamento com <strong>baixo desperd\u00edcio<\/strong>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1542\" height=\"867\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-rubber-vulcanization.jpg\" alt=\"\" class=\"wp-image-784\" srcset=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-rubber-vulcanization.jpg 1542w, https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-rubber-vulcanization-768x432.jpg 768w, https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-rubber-vulcanization-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1542px) 100vw, 1542px\" \/><figcaption class=\"wp-element-caption\">O processamento de materiais com propriedades elastom\u00e9ricas mudou muito ao longo dos s\u00e9culos e d\u00e9cadas. A vulcaniza\u00e7\u00e3o da borracha \u00e9 um processo que consome muito tempo e energia.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1542\" height=\"867\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-injection-molding.jpg\" alt=\"\" class=\"wp-image-782\" srcset=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-injection-molding.jpg 1542w, https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-injection-molding-768x432.jpg 768w, https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/10\/kuraray-elastomer-styrenic-block-copolymers-injection-molding-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1542px) 100vw, 1542px\" \/><figcaption class=\"wp-element-caption\">Hoje, materiais como SBCs podem ser processados em escala industrial, utilizando t\u00e9cnicas como moldagem por inje\u00e7\u00e3o.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_s bg_orange circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\">SBCs vs. outros materiais<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs s\u00e3o elast\u00f4meros termopl\u00e1sticos <strong>sem reticula\u00e7\u00f5es<\/strong>, ao contr\u00e1rio de silicones, EPDM e borrachas naturais. No entanto, os SBCs exibem <strong>propriedades el\u00e1sticas<\/strong> devido \u00e0 sua estrutura molecular.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\">Uma breve hist\u00f3ria dos copol\u00edmeros em bloco de estireno<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1962, uma das primeiras patentes de SBCs foi registrada pela Shell USA Inc. (US3265765). Em 1964, os copol\u00edmeros tri-blocos estireno-butadieno-estireno (SBS) foram fabricados na planta piloto da Shell, e no ano seguinte foram comercializados pela Shell. O primeiro cliente de SBS foi a Scotty Shoes, um fabricante de cal\u00e7ados em Massachusetts. Ainda em 1964, foi registrado uma das primeiras patentes de copol\u00edmero em bloco de estireno hidrogenado (HSBC) (US3431323). No final dos anos 1960, os HSBCs se tornaram dispon\u00edveis em escala comercial.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\">Como \u00e9 feito<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs s\u00e3o feitos por <strong>polimeriza\u00e7\u00e3o ani\u00f4nica<\/strong>, uma t\u00e9cnica vers\u00e1til e poderosa para a s\u00edntese de pol\u00edmeros com estruturas bem projetadas e propriedades do material sob medida.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_yellow circle_top_right\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\">Tipos de SBCs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existem 2 categorias de SBCs:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Copol\u00edmeros em bloco de estireno n\u00e3o hidrogenados (USBCs)<\/li>\n\n\n\n<li>Copol\u00edmeros em bloco de estireno hidrogenados (HSBCs)<\/li>\n<\/ol>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">O que s\u00e3o USBCs?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os copol\u00edmeros em bloco de estireno n\u00e3o hidrogenados (USBCs) consistem em unidades de mon\u00f4meros de estireno e dieno dispostas em uma estrutura semelhante a um bloco. O bloco de dieno pode ser polibutadieno (PB) ou poliisopreno (PI). Os USBCs <strong>n\u00e3o passaram por nenhum processo de hidrogena\u00e7\u00e3o<\/strong>, portanto, ret\u00eam seu <strong>bloco dieno insaturado.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso os torna <strong>mais reativos<\/strong> em compara\u00e7\u00e3o com seus hom\u00f3logos hidrogenados, permitindo uma <strong>personaliza\u00e7\u00e3o<\/strong> adicional por meio de rea\u00e7\u00f5es qu\u00edmicas como reticula\u00e7\u00e3o ou funcionaliza\u00e7\u00e3o. Eles exibem <strong>excelentes propriedades elastom\u00e9ricas<\/strong> e <strong>custos de processamento mais baixos<\/strong> em compara\u00e7\u00e3o com os HSBCs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, devido ao dieno insaturado e \u00e0 suscetibilidade \u00e0 degrada\u00e7\u00e3o, apresentam <strong>menor estabilidade t\u00e9rmica<\/strong>, <strong>menor resist\u00eancia qu\u00edmica<\/strong> e s\u00e3o mais <strong>suscet\u00edveis ao envelhecimento<\/strong>. Os USBCs tendem a desenvolver um <strong>tom amarelado<\/strong> com o tempo, o que pode n\u00e3o ser cr\u00edtico para algumas aplica\u00e7\u00f5es, mas \u00e9 problem\u00e1tico para outras \u2013 como embalagem e aplica\u00e7\u00f5es m\u00e9dicas, onde <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/kurarity-transparent-tpe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TPEs transparentes<\/strong><\/a> s\u00e3o preferidos.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading\">Tipos de USBCs<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Abr.<\/strong><\/td><td><strong>Estrutura molecular<\/strong><\/td><td><strong>Produtos da Kuraray<\/strong><\/td><\/tr><tr><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/sebs\/\" target=\"_blank\" data-type=\"post\" data-id=\"539\" rel=\"noreferrer noopener\">SBS<\/a><\/td><td>Copol\u00edmero em bloco de estireno-butadieno-estireno<\/td><td>N\/A<\/td><\/tr><tr><td>SIS<\/td><td>Copol\u00edmero em bloco de estireno-isopreno-estireno<\/td><td>N\/A<\/td><\/tr><tr><td>V-SIS<\/td><td>Copol\u00edmero em bloco de estireno-isopreno-estireno rico em vinil<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/hybrar\/#non-hydrogenated\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/hybrar\/#non-hydrogenated\" rel=\"noreferrer noopener\">HYBRAR\u2122 5000-series<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_cyan circle_top_right\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">O que s\u00e3o HSBCs?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os copol\u00edmeros em bloco de estireno hidrogenados (HSBCs) <strong>passam por um processo de hidrogena\u00e7\u00e3o<\/strong>, que adiciona hidrog\u00eanio para <strong>saturar<\/strong> quimicamente as liga\u00e7\u00f5es insaturadas no bloco de dieno. Isto converte o bloco de dieno em um bloco <strong>saturado<\/strong>, tal como etileno\/butileno (EB), etileno\/propileno (EP) e etileno\/etileno\/propileno (EEP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado, os HSBCs <strong>apresentam melhor estabilidade t\u00e9rmica, durabilidade, resist\u00eancia \u00e0s intemp\u00e9ries, resist\u00eancia qu\u00edmica e resist\u00eancia aos raios UV <\/strong>em compara\u00e7\u00e3o com os USBCs. Eles tamb\u00e9m sofrem significativamente <strong>menos amarelamento<\/strong>. Eles podem ser a melhor op\u00e7\u00e3o de material para aplica\u00e7\u00f5es particularmente exigentes em ind\u00fastrias como <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/automotive-polymers\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>automotivo<\/strong><\/a>, <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/electronics\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>eletr\u00f4nico<\/strong><\/a> e <strong><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/medical-grade-tpe\/\" target=\"_blank\" rel=\"noreferrer noopener\">o m\u00e9dico hospitalar<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devido \u00e0 etapa adicional de hidrogena\u00e7\u00e3o, os HSBCs podem apresentar <strong>custos de processamento mais altos em compara\u00e7\u00e3o com os<\/strong> USBCs. Uma vez hidrogenados, os SBCs t\u00eam <strong>reatividade reduzida<\/strong>, o que limita a disponibilidade de modifica\u00e7\u00f5es qu\u00edmicas adicionais ou op\u00e7\u00f5es de reticula\u00e7\u00e3o.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/kuraray-elastomer-styrenic-block-copolymers-pellets.jpg\" alt=\"\" class=\"wp-image-91\" srcset=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/kuraray-elastomer-styrenic-block-copolymers-pellets.jpg 1200w, https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/kuraray-elastomer-styrenic-block-copolymers-pellets-768x403.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Pellets HSBC<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Tipos de HSBCs<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Abr.<\/strong><\/td><td><strong>Estrutura molecular<\/strong><\/td><td><strong>Produtos da Kuraray<\/strong><\/td><\/tr><tr><td>SEP<\/td><td>Copol\u00edmero em bloco de estireno-etileno\/propileno<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/#s-1000\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/septon\/#s-1000\" rel=\"noreferrer noopener\">SEPTON\u2122 1000-series<\/a><\/td><\/tr><tr><td>SEPS<\/td><td>Copol\u00edmero em bloco de estireno-etileno\/propileno-estireno<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/#s-2000\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/septon\/#s-2000\" rel=\"noreferrer noopener\">SEPTON\u2122 2000-series<\/a><\/td><\/tr><tr><td>SEEPS<\/td><td>Copol\u00edmero em bloco de estireno-etileno\/etileno\/propileno-estireno<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/#s-4000\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/septon\/#s-4000\" rel=\"noreferrer noopener\">SEPTON\u2122 4000-series<\/a><\/td><\/tr><tr><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/sebs\/\" target=\"_blank\" data-type=\"post\" data-id=\"539\" rel=\"noreferrer noopener\">SEBS<\/a><\/td><td>Copol\u00edmero em bloco de estireno-etileno\/butileno-estireno<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/#s-8000\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/septon\/#s-8000\" rel=\"noreferrer noopener\">SEPTON\u2122 8000-series<\/a><\/td><\/tr><tr><td>V-SEPS<\/td><td>SEPS rico em vinil<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/hybrar\/#hydrogenated\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/hybrar\/#hydrogenated\" rel=\"noreferrer noopener\">HYBRAR\u2122 7125F<\/a><\/td><\/tr><tr><td>V-SEEPS<\/td><td>SEEPS rico em vinil<\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/hybrar\/#hydrogenated\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/hybrar\/#hydrogenated\" rel=\"noreferrer noopener\">HYBRAR\u2122 7311F<\/a><\/td><\/tr><tr><td>Grades Especiais<\/td><td><\/td><td><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-v-series\/\" target=\"_blank\" data-type=\"page\" data-id=\"332\" rel=\"noreferrer noopener\">SEPTON\u2122 V-series<\/a><br><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-j-series\/\" target=\"_blank\" data-type=\"page\" data-id=\"334\" rel=\"noreferrer noopener\">SEPTON\u2122 J-series<\/a><br><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-q-series-insulated-cable-material\/\" target=\"_blank\" data-type=\"page\" data-id=\"333\" rel=\"noreferrer noopener\">SEPTON\u2122 Q-series<\/a><br><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-bio-series\/\" target=\"_blank\" data-type=\"page\" data-id=\"331\" rel=\"noreferrer noopener\">SEPTON\u2122 BIO-series<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"applications\">Aplica\u00e7\u00f5es dos SBCs<\/h2>\n\n\n\n<div id=\"applications-feed\" class=\"wp-block-group columns-teaser has-vivid-green-cyan-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/adhesives-coatings-sealants\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/08\/adhesives-coatings-sealants-elastomers-application-tape.jpg\" alt=\"\" class=\"wp-image-337\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Adesivos, revestimentos e selantes<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/adhesives-coatings-sealants\/\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/compounding\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/compounding-rubber-elastomers-polymers-application.jpg\" alt=\"Compounding\" class=\"wp-image-46\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Compostos<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/compounding\/\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/consumer-goods\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/consumer-goods-elastomers-application-diaper-baby.jpg\" alt=\"\" class=\"wp-image-52\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Bens de consumo<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/consumer-goods\/\" data-type=\"page\" data-id=\"46\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/electronics\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/electronics-elastomers-application-cable-protection.jpg\" alt=\"Electronics\" class=\"wp-image-48\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Eletr\u00f4nicos<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/electronics\/\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/industrial-and-construction\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/industrial-construction-elastomers-application-mortar.jpg\" alt=\"\" class=\"wp-image-44\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ind\u00fastria e constru\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/industrial-and-construction\/\" data-type=\"page\" data-id=\"52\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/medical-grade-tpe\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/medical-grade-tpe-application-tubing.jpg\" alt=\"Medical\" class=\"wp-image-42\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e9dico Hospitalar<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/medical-grade-tpe\/\" data-type=\"page\" data-id=\"53\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/automotive-polymers\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/automotive-polymers-mobility-elastomers-application-baby-car.jpg\" alt=\"Mobility\" class=\"wp-image-40\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mobilidade<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/automotive-polymers\/\" data-type=\"page\" data-id=\"54\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/oil-modification\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/oil-modification-elastomers-application-liquid.jpg\" alt=\"Oil Modification\" class=\"wp-image-39\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Modifica\u00e7\u00e3o de \u00f3leo<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/oil-modification\/\" data-type=\"page\" data-id=\"55\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/diaper-elastics\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/07\/diaper-elastics-personal-care-hygiene-small.jpg\" alt=\"\" class=\"wp-image-290\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Cuidados pessoais e higiene<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/diaper-elastics\/\" data-type=\"page\" data-id=\"1791\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/sporting-goods-and-footwear\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/sporting-goods-footwear-elastomers-application-swimmer.jpg\" alt=\"Sporting Goods &amp; Footwear\" class=\"wp-image-37\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Artigos esportivos e cal\u00e7ados<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/sporting-goods-and-footwear\/\" data-type=\"page\" data-id=\"56\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/3d-printing\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/3d-printing-elastomers-application-additive-manufacturing.jpg\" alt=\"3D Printing\" class=\"wp-image-50\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Impress\u00e3o 3D<\/h3>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/3d-printing\/\" data-type=\"page\" data-id=\"47\">Leia mais<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Descubra os SBCs da Kuraray<\/h2>\n\n\n\n<div class=\"wp-block-group columns-teaser has-vivid-green-cyan-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/kuraray-septon-hsbc-tpe-clear-pellets.jpg\" alt=\"\" class=\"wp-image-56\"\/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">SEPTON\u2122<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">TPE de alto desempenho<\/p>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon\/\" data-type=\"page\" data-id=\"43\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download tile_green has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-bio-series\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/07\/septon-bio-series-tpe.jpg\" alt=\"\" class=\"wp-image-294\"\/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">SEPTON\u2122 BIO-series<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">TPE de base biol\u00f3gica<\/p>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/septon-bio-series\/\" data-type=\"page\" data-id=\"331\">Leia mais<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group tile_download has-pale-cyan-blue-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full download_img\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/hybrar\/\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"273\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/05\/hybrar-tpe-sbc-pellets.jpg\" alt=\"\" class=\"wp-image-64\"\/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">HYBRAR\u2122<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">TPE de alto desempenho rico em vinil<\/p>\n\n\n\n<p class=\"link_downloads wp-block-paragraph\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/products\/hybrar\/\" data-type=\"page\" data-id=\"39\">Leia mais<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"circle_s bg_cyan circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">SBCs de grau m\u00e9dico<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Certos grades de SBCs atendem aos requisitos regulamentares e s\u00e3o certificados para aplica\u00e7\u00f5es m\u00e9dicas em diferentes usos (por exemplo, contato com a pele, contato com sangue, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mais informa\u00e7\u00f5es, visite nossa p\u00e1gina sobre <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/medical-grade-tpe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TPEs de grau m\u00e9dico<\/strong><\/a> ou <strong><a href=\"#contact\">entre em contato conosco<\/a><\/strong>. Nossos especialistas ter\u00e3o prazer em aconselh\u00e1-lo.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/pt\/wp-content\/uploads\/sites\/6\/2024\/09\/medical-grade-tpe-device-tubing.jpg\" alt=\"\" class=\"wp-image-518\"\/><figcaption class=\"wp-element-caption\"><strong><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/what-are-elastomers\/\" target=\"_blank\" rel=\"noreferrer noopener\">Elast\u00f4meros<\/a><\/strong> em dispositivos m\u00e9dicos e tubos<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">SBCs em adesivos hot melt<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adesivos hot melt \u00e9 uma outra aplica\u00e7\u00e3o comum para SBCs. Os SBCs s\u00e3o um componente essencial para fornecer <strong>propriedades adesivas<\/strong>. A Kuraray oferece materiais com excelentes caracter\u00edsticas de processabilidade e desempenho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recursos adicionais sobre adesivos hot melt podem ser encontrados aqui:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/adhesives-coatings-sealants\/\" data-type=\"page\" data-id=\"45\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Adesivos, revestimentos e selantes<\/strong><\/a><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/polymer-adhesives\/\" target=\"_blank\" rel=\"noreferrer noopener\">Adesivos polim\u00e9ricos<\/a><\/strong><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_beige circle_top_right\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">SBCs utilizados para modifica\u00e7\u00e3o de pol\u00edmeros<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os SBCs oferecem ampla versatilidade, permitindo que os clientes ajustem seus pol\u00edmeros para <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>aplica\u00e7\u00f5es<\/strong><\/a> espec\u00edficas em uma variedade de ind\u00fastrias. De <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/automotive-polymers\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>componentes automotivos<\/strong><\/a> a materiais de embalagem, <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/industrial-and-construction\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>de produtos de constru\u00e7\u00e3o<\/strong><\/a> a <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/applications\/consumer-goods\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>bens de consumo<\/strong><\/a>, os SBCs provaram seu valor em in\u00fameras solu\u00e7\u00f5es inovadoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao incorporar SBCs em misturas de pol\u00edmeros, os clientes podem melhorar a vida \u00fatil e a durabilidade dos produtos, reduzindo a necessidade de substitui\u00e7\u00f5es frequentes e minimizando o desperd\u00edcio. SBCs podem ser \u00fateis como modificadores para polipropileno (PP), polietileno (PE), poliestireno (PS), policarbonato (PC), resinas acrilonitrila-butadieno-estireno (ABS) e \u00e9ter polifenileno (PPE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A resist\u00eancia ao impacto e a flexibilidade aprimoradas proporcionadas pelos SBCs contribuem para produtos mais duradouros e resistentes, resultando na redu\u00e7\u00e3o do impacto ambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os SBCs possibilitam a cria\u00e7\u00e3o de solu\u00e7\u00f5es polim\u00e9ricas leves, mas resistentes, reduzindo o consumo total de material e a pegada de carbono. Sua versatilidade permite caracter\u00edsticas de processamento otimizadas, diminuindo o consumo de energia durante os processos de fabrica\u00e7\u00e3o. Saiba mais sobre SBCs como <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/polymer-modification\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>modificadores de pol\u00edmeros<\/strong><\/a>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">SBCs utilizados como melhoradores do \u00edndice de viscosidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quando se trata de obter perfis de viscosidade precisos, os SBCs se destacam como <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/viscosity-index-improver\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>modificadores de viscosidade<\/strong><\/a> altamente eficientes e vers\u00e1teis. Esses pol\u00edmeros t\u00eam a capacidade de alterar significativamente a viscosidade dos \u00f3leos lubrificantes em baixas concentra\u00e7\u00f5es, proporcionando capacidades excepcionais de espessamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das caracter\u00edsticas de destaque dos SBCs \u00e9 a sua estabilidade ao cisalhamento, garantindo que a viscosidade permane\u00e7a consistente em diversas condi\u00e7\u00f5es de temperaturas e cisalhamento. Isto os torna ideais para aplica\u00e7\u00f5es que envolvem for\u00e7as mec\u00e2nicas intensas, onde a estabilidade e o controle confi\u00e1vel do fluxo s\u00e3o cruciais. Saiba mais sobre os SBCs como <a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/viscosity-index-improver\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>melhoradores do \u00edndice de viscosidade<\/strong><\/a>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"contact\" class=\"wp-block-group holder_contact has-cyan-bluish-gray-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"heading_contact wp-block-paragraph\">Contato<\/p>\n\n\n\n<form class=\"contact_form\" name=\"contact_form\" method=\"post\" onsubmit=\"return validateForm(this);\">\n<div class=\"form-group\">\n<label>Empresa *<\/label> \n<input type=\"text\" class=\"form-control\" name=\"company\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>Pa\u00eds *<\/label> \n<select class=\"form-control\" name=\"country\" required=\"required\">\n<option value=\"\">Selecione seu pa\u00eds&#8230;<\/option>\n<option value=\"Afghanistan\">Afghanistan<\/option>\n<option value=\"Aland Islands\">Aland Islands<\/option>\n<option value=\"Albania\">Albania<\/option>\n<option value=\"Algeria\">Algeria<\/option>\n<option value=\"American Samoa\">American Samoa<\/option>\n<option value=\"Andorra\">Andorra<\/option>\n<option value=\"Angola\">Angola<\/option>\n<option value=\"Anguilla\">Anguilla<\/option>\n<option value=\"Antigua and Barbuda\">Antigua and Barbuda<\/option>\n<option value=\"Argentina\">Argentina<\/option>\n<option value=\"Armenia\">Armenia<\/option>\n<option value=\"Aruba\">Aruba<\/option>\n<option value=\"Australia\">Australia<\/option>\n<option value=\"Austria\">Austria<\/option>\n<option value=\"Azerbaijan\">Azerbaijan<\/option>\n<option value=\"Bahamas\">Bahamas<\/option>\n<option value=\"Bahrain\">Bahrain<\/option>\n<option value=\"Bangladesh\">Bangladesh<\/option>\n<option value=\"Barbados\">Barbados<\/option>\n<option value=\"Belarus\">Belarus<\/option>\n<option value=\"Belgium\">Belgium<\/option>\n<option value=\"Belize\">Belize<\/option>\n<option value=\"Benin\">Benin<\/option>\n<option value=\"Bermuda\">Bermuda<\/option>\n<option value=\"Bhutan\">Bhutan<\/option>\n<option value=\"Bolivia\">Bolivia<\/option>\n<option value=\"Bonaire\">Bonaire<\/option>\n<option value=\"Bosnia and Herzegovina\">Bosnia and Herzegovina<\/option>\n<option value=\"Botswana\">Botswana<\/option>\n<option value=\"Bouvet Island\">Bouvet Island<\/option>\n<option value=\"Brazil\">Brazil<\/option>\n<option value=\"British Indian Ocean Territory\">British Indian Ocean Territory<\/option>\n<option value=\"Brunei Darussalam\">Brunei Darussalam<\/option>\n<option value=\"Bulgaria\">Bulgaria<\/option>\n<option value=\"Burkina Faso\">Burkina Faso<\/option>\n<option value=\"Burundi\">Burundi<\/option>\n<option value=\"Cambodia\">Cambodia<\/option>\n<option value=\"Cameroon\">Cameroon<\/option>\n<option value=\"Canada\">Canada<\/option>\n<option value=\"Cape Verde\">Cape Verde<\/option>\n<option value=\"Cayman Islands\">Cayman Islands<\/option>\n<option value=\"Central African Republic\">Central African Republic<\/option>\n<option value=\"Chad\">Chad<\/option>\n<option value=\"Chile\">Chile<\/option>\n<option value=\"China\">China<\/option>\n<option value=\"Christmas Island\">Christmas Island<\/option>\n<option value=\"Cocos (Keeling) Islands\">Cocos (Keeling) Islands<\/option>\n<option value=\"Colombia\">Colombia<\/option>\n<option value=\"Comoros\">Comoros<\/option>\n<option value=\"Congo\">Congo<\/option>\n<option value=\"Cook Islands\">Cook Islands<\/option>\n<option value=\"Costa Rica\">Costa Rica<\/option>\n<option value=\"Cote d'Ivoire\">Cote d&#8217;Ivoire<\/option>\n<option value=\"Croatia\">Croatia<\/option>\n<option value=\"Cuba\">Cuba<\/option>\n<option value=\"Curacao\">Curacao<\/option>\n<option value=\"Cyprus\">Cyprus<\/option>\n<option value=\"Czech Republic\">Czech Republic<\/option>\n<option value=\"Democratic Republic of the Congo\">Democratic Republic of the Congo<\/option>\n<option value=\"Denmark\">Denmark<\/option>\n<option value=\"Djibouti\">Djibouti<\/option>\n<option value=\"Dominica\">Dominica<\/option>\n<option value=\"Dominican Republic\">Dominican Republic<\/option>\n<option value=\"Ecuador\">Ecuador<\/option>\n<option value=\"Egypt\">Egypt<\/option>\n<option value=\"El Salvador\">El Salvador<\/option>\n<option value=\"Equatorial Guinea\">Equatorial Guinea<\/option>\n<option value=\"Eritrea\">Eritrea<\/option>\n<option value=\"Estonia\">Estonia <\/option>\n<option value=\"Eswatini\">Eswatini<\/option>\n<option value=\"Ethiopia\">Ethiopia<\/option>\n<option value=\"Falkland Islands (Malvinas)\">Falkland Islands (Malvinas)<\/option>\n<option value=\"Faroe Islands\">Faroe Islands<\/option>\n<option value=\"Fiji\">Fiji<\/option>\n<option value=\"Finland\">Finland<\/option>\n<option value=\"France\">France<\/option>\n<option value=\"French Guiana\">French Guiana<\/option>\n<option value=\"French Polynesia\">French Polynesia<\/option>\n<option value=\"French Southern Territories\">French Southern Territories<\/option>\n<option value=\"Gabon\">Gabon<\/option>\n<option value=\"Gambia\">Gambia<\/option>\n<option value=\"Georgia\">Georgia<\/option>\n<option value=\"Germany\">Germany<\/option>\n<option value=\"Ghana\">Ghana<\/option>\n<option value=\"Gibraltar\">Gibraltar<\/option>\n<option value=\"Greece\">Greece<\/option>\n<option value=\"Greenland\">Greenland<\/option>\n<option value=\"Grenada\">Grenada<\/option>\n<option value=\"Guadeloupe\">Guadeloupe<\/option>\n<option value=\"Guam\">Guam<\/option>\n<option value=\"Guatemala\">Guatemala<\/option>\n<option value=\"Guernsey\">Guernsey<\/option>\n<option value=\"Guinea\">Guinea<\/option>\n<option value=\"Guinea-Bissau\">Guinea-Bissau<\/option>\n<option value=\"Guyana\">Guyana<\/option>\n<option value=\"Haiti\">Haiti<\/option>\n<option value=\"Heard Island and McDonald Islands\">Heard Island and McDonald Islands<\/option>\n<option value=\"Holy See (Vatican City State)\">Holy See (Vatican City State)<\/option>\n<option value=\"Honduras\">Honduras<\/option>\n<option value=\"Hong Kong\">Hong Kong<\/option>\n<option value=\"Hungary\">Hungary<\/option>\n<option value=\"Iceland\">Iceland<\/option>\n<option value=\"India\">India<\/option>\n<option value=\"Indonesia\">Indonesia<\/option>\n<option value=\"Iran\">Iran<\/option>\n<option value=\"Iraq\">Iraq<\/option>\n<option value=\"Ireland\">Ireland<\/option>\n<option value=\"Isle of Man\">Isle of Man<\/option>\n<option value=\"Israel\">Israel<\/option>\n<option value=\"Italy\">Italy<\/option>\n<option value=\"Jamaica\">Jamaica<\/option>\n<option value=\"Japan\">Japan<\/option>\n<option value=\"Jersey\">Jersey<\/option>\n<option value=\"Jordan\">Jordan<\/option>\n<option value=\"Kazakhstan\">Kazakhstan<\/option>\n<option value=\"Kenya\">Kenya<\/option>\n<option value=\"Kiribati\">Kiribati<\/option>\n<option value=\"Korea, Democratic People's Republic of\">Korea, Democratic People&#8217;s Republic of<\/option>\n<option value=\"Korea, Republic of\">Korea(Republic of Korea)<\/option>\n<option value=\"Kosovo\">Kosovo<\/option>\n<option value=\"Kuwait\">Kuwait<\/option>\n<option value=\"Kyrgyzstan\">Kyrgyzstan<\/option>\n<option value=\"Lao People's Democratic Republic\">Lao People&#8217;s Democratic Republic<\/option>\n<option value=\"Latvia\">Latvia<\/option>\n<option value=\"Lebanon\">Lebanon<\/option>\n<option value=\"Lesotho\">Lesotho<\/option>\n<option value=\"Liberia\">Liberia<\/option>\n<option value=\"Libya\">Libya<\/option>\n<option value=\"Liechtenstein\">Liechtenstein<\/option>\n<option value=\"Lithuania\">Lithuania<\/option>\n<option value=\"Luxembourg\">Luxembourg<\/option>\n<option value=\"Macau\">Macau<\/option>\n<option value=\"Macedonia\">Macedonia<\/option>\n<option value=\"Madagascar\">Madagascar<\/option>\n<option value=\"Malawi\">Malawi<\/option>\n<option value=\"Malaysia\">Malaysia<\/option>\n<option value=\"Maldives\">Maldives<\/option>\n<option value=\"Mali\">Mali<\/option>\n<option value=\"Malta\">Malta<\/option>\n<option value=\"Marshall Islands\">Marshall Islands<\/option>\n<option value=\"Martinique\">Martinique<\/option>\n<option value=\"Mauritania\">Mauritania<\/option>\n<option value=\"Mauritius\">Mauritius<\/option>\n<option value=\"Mayotte\">Mayotte<\/option>\n<option value=\"Mexico\">Mexico<\/option>\n<option value=\"Micronesia\">Micronesia<\/option>\n<option value=\"Moldova\">Moldova<\/option>\n<option value=\"Monaco\">Monaco<\/option>\n<option value=\"Mongolia\">Mongolia<\/option>\n<option value=\"Montenegro\">Montenegro<\/option>\n<option value=\"Montserrat\">Montserrat<\/option>\n<option value=\"Morocco\">Morocco<\/option>\n<option value=\"Mozambique\">Mozambique<\/option>\n<option value=\"Myanmar\">Myanmar<\/option>\n<option value=\"Namibia\">Namibia<\/option>\n<option value=\"Nauru\">Nauru<\/option>\n<option value=\"Nepal\">Nepal<\/option>\n<option value=\"Netherlands\">Netherlands<\/option>\n<option value=\"New Caledonia\">New Caledonia<\/option>\n<option value=\"New Zealand\">New Zealand<\/option>\n<option value=\"Nicaragua\">Nicaragua<\/option>\n<option value=\"Niger\">Niger<\/option>\n<option value=\"Nigeria\">Nigeria<\/option>\n<option value=\"Niue\">Niue<\/option>\n<option value=\"Norfolk Island\">Norfolk Island<\/option>\n<option value=\"Northern Mariana Islands\">Northern Mariana Islands<\/option>\n<option value=\"Norway\">Norway<\/option>\n<option value=\"Oman\">Oman<\/option>\n<option value=\"Pakistan\">Pakistan<\/option>\n<option value=\"Palau\">Palau<\/option>\n<option value=\"Palestinian Territory\">Palestinian Territory<\/option>\n<option value=\"Panama\">Panama<\/option>\n<option value=\"Papua New Guinea\">Papua New Guinea<\/option>\n<option value=\"Paraguay\">Paraguay<\/option>\n<option value=\"Peru\">Peru<\/option>\n<option value=\"Philippines\">Philippines<\/option>\n<option value=\"Pitcairn\">Pitcairn<\/option>\n<option value=\"Poland\">Poland<\/option>\n<option value=\"Portugal\">Portugal<\/option>\n<option value=\"Puerto Rico\">Puerto Rico<\/option>\n<option value=\"Qatar\">Qatar<\/option>\n<option value=\"Reunion\">Reunion<\/option>\n<option value=\"Romania\">Romania<\/option>\n<option value=\"Russian Federation\">Russian Federation<\/option>\n<option value=\"Rwanda\">Rwanda<\/option>\n<option value=\"Saint Barthelemy\">Saint Barthelemy<\/option>\n<option value=\"Saint Helena\">Saint Helena<\/option>\n<option value=\"Saint Kitts and Nevis\">Saint Kitts and Nevis<\/option>\n<option value=\"Saint Lucia\">Saint Lucia<\/option>\n<option value=\"Saint Martin (French part)\">Saint Martin (French part)<\/option>\n<option value=\"Saint Pierre and Miquelon\">Saint Pierre and Miquelon<\/option>\n<option value=\"Saint Vincent and the Grenadines\">Saint Vincent and the Grenadines<\/option>\n<option value=\"Samoa\">Samoa<\/option>\n<option value=\"San Marino\">San Marino<\/option>\n<option value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option>\n<option value=\"Saudi Arabia\">Saudi Arabia<\/option>\n<option value=\"Senegal\">Senegal<\/option>\n<option value=\"Serbia\">Serbia<\/option>\n<option value=\"Seychelles\">Seychelles<\/option>\n<option value=\"Sierra Leone\">Sierra Leone<\/option>\n<option value=\"Singapore\">Singapore<\/option>\n<option value=\"Sint Maarten (Dutch part)\">Sint Maarten (Dutch part)<\/option>\n<option value=\"Slovakia\">Slovakia<\/option>\n<option value=\"Slovenia\">Slovenia<\/option>\n<option value=\"Solomon Islands\">Solomon Islands<\/option>\n<option value=\"Somalia\">Somalia<\/option>\n<option value=\"South Africa\">South Africa<\/option>\n<option value=\"South Georgia and the South Sandwich Isl\">South Georgia and the South Sandwich Isl<\/option>\n<option value=\"South Sudan\">South Sudan<\/option>\n<option value=\"Spain\">Spain<\/option>\n<option value=\"Sri Lanka\">Sri Lanka<\/option>\n<option value=\"Sudan\">Sudan<\/option>\n<option value=\"Suriname\">Suriname<\/option>\n<option value=\"Svalbard and Jan Mayen\">Svalbard and Jan Mayen<\/option>\n<option value=\"Sweden\">Sweden<\/option>\n<option value=\"Switzerland\">Switzerland<\/option>\n<option value=\"Syrian Arab Republic\">Syrian Arab Republic<\/option>\n<option value=\"Taiwan\">Taiwan<\/option>\n<option value=\"Tajikistan\">Tajikistan<\/option>\n<option value=\"Tanzania\">Tanzania<\/option>\n<option value=\"Thailand\">Thailand<\/option>\n<option value=\"Timor-Leste\">Timor-Leste<\/option>\n<option value=\"Togo\">Togo<\/option>\n<option value=\"Tokelau\">Tokelau<\/option>\n<option value=\"Tonga\">Tonga<\/option>\n<option value=\"Trinidad and Tobago\">Trinidad and Tobago<\/option>\n<option value=\"Tunisia\">Tunisia<\/option>\n<option value=\"Turkey\">Turkey<\/option>\n<option value=\"Turkmenistan\">Turkmenistan<\/option>\n<option value=\"Turks and Caicos Islands\">Turks and Caicos Islands<\/option>\n<option value=\"Tuvalu\">Tuvalu<\/option>\n<option value=\"Uganda\">Uganda<\/option>\n<option value=\"Ukraine\">Ukraine<\/option>\n<option value=\"United Arab Emirates\">United Arab Emirates<\/option>\n<option value=\"United Kingdom\">United Kingdom<\/option>\n<option value=\"United States\">United States<\/option>\n<option value=\"United States Minor Outlying Islands\">United States Minor Outlying Islands<\/option>\n<option value=\"Uruguay\">Uruguay<\/option>\n<option value=\"Uzbekistan\">Uzbekistan<\/option>\n<option value=\"Vanuatu\">Vanuatu<\/option>\n<option value=\"Venezuela\">Venezuela<\/option>\n<option value=\"Viet Nam\">Viet Nam<\/option>\n<option value=\"Virgin Islands, British\">Virgin Islands, British<\/option>\n<option value=\"Virgin Islands, U.S.\">Virgin Islands, U.S.<\/option>\n<option value=\"Wallis and Futuna\">Wallis and Futuna<\/option>\n<option value=\"Western Sahara\">Western Sahara<\/option>\n<option value=\"Yemen\">Yemen<\/option>\n<option value=\"Zambia\">Zambia<\/option>\n<option value=\"Zimbabwe\">Zimbabwe<\/option>\n<\/select>\n<\/div>\n\n<div class=\"form-group\">\n<label>Nome *<\/label>\n<input type=\"text\" class=\"form-control\" name=\"first_name\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>Sobrenome *<\/label>\n<input type=\"text\" class=\"form-control\" name=\"last_name\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>E-mail *<\/label>\n<input type=\"email\" class=\"form-control\" name=\"email\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label for=\"phone\">N\u00famero de telefone<\/label>\n<input type=\"tel\" class=\"form-control\" id=\"phone\" name=\"phone\"> \n<\/div>\n\n<div class=\"form-group\">\n<label>Mensagem *<\/label> \n<textarea class=\"form-control\" name=\"txt_Isp_Elas_Inquiry\" placeholder=\"\" required=\"required\"><\/textarea>\n<\/div>\n\n<div style=\"position:absolute; left:-9999px; top:-9999px\">\n<label for=\"pardot_extra_field\">Comments<\/label>\n<input type=\"text\" id=\"pardot_extra_field\" name=\"pardot_extra_field\">\n<\/div>\n  \n<div class=\"form-accepts\">\nConsulte o <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de Privacidade do Cliente<\/a> para saber como o Grupo Kuraray lida com informa\u00e7\u00f5es pessoais relacionadas a atividades de vendas e marketing.<br>\nSe voc\u00ea concorda com o <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de Privacidade do Cliente<\/a>, marque a caixa e envie sua solicita\u00e7\u00e3o.<br>\nConsulte a <a href=\"https:\/\/www.kuraray.com\/privacy\/\" target=\"blank\" rel=\"noopener\">Pol\u00edtica de Privacidade<\/a> e a <a href=\"https:\/\/www.elastomer.kuraray.com\/cookie-policy\/\" target=\"blank\" rel=\"noopener\">Pol\u00edtica de Cookies<\/a> ara o tratamento de outras informa\u00e7\u00f5es pessoais.<br>\n<\/div>\n\n<div class=\"form-accepts\">\n<label class=\"switch\" for=\"checkbox\">\n    <input type=\"checkbox\" id=\"checkbox\" name=\"privacynotice\" value=\"true\" required=\"required\" oninvalid=\"this.setCustomValidity('Por favor, preencha este campo.')\" onchange=\"this.setCustomValidity('')\">\n    <div class=\"slider round\"><\/div>\n  <\/label>\n <div class=\"switchlabel\">Concordo com o <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de Privacidade do Cliente<\/a>. *<\/div>\n<\/div>\n  \n<div class=\"form-submit\">\n<div class=\"required footnote\">* Obrigat\u00f3rio<\/div>\n<input type=\"submit\" class=\"Submitbutton\" name=\"submit\" value=\"Enviar\">\n<\/div>\n<\/form>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os copol\u00edmeros em bloco de estireno (SBCs) s\u00e3o materiais TPE populares que combinam uma elasticidade semelhante \u00e0 da borracha com a excelente processabilidade dos termopl\u00e1sticos.<br class=\"break-more-link\"><br class=\"break-more-link\"><a href=\"https:\/\/www.elastomer.kuraray.com\/pt\/blog\/styrenic-block-copolymer\/\" class=\"more-link\">Leia mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":91,"comment_status":"closed","ping_status":"open","sticky":false,"template":"single-blog.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-90","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":1,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":1373,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/posts\/90\/revisions\/1373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/media\/91"}],"wp:attachment":[{"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/pt\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}