{"id":159,"date":"2021-03-05T16:07:17","date_gmt":"2021-03-05T15:07:17","guid":{"rendered":"https:\/\/www.elastomer.kuraray.com\/es\/applications\/3d-printing\/"},"modified":"2026-06-04T16:26:17","modified_gmt":"2026-06-04T14:26:17","slug":"3d-printing","status":"publish","type":"page","link":"https:\/\/www.elastomer.kuraray.com\/es\/applications\/3d-printing\/","title":{"rendered":"Impresi\u00f3n en 3D"},"content":{"rendered":"\n<div class=\"circle_b bg_orange circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading\">Elast\u00f3meros en impresi\u00f3n 3D<\/h1>\n\n\n\n<div class=\"wp-block-group holder_author has-light-green-cyan-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-post-author\"><div class=\"wp-block-post-author__content\"><p class=\"wp-block-post-author__byline\">Autor<\/p><p class=\"wp-block-post-author__name\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/author\/robin-conrad\/\" target=\"_self\">Robin Conrad<\/a><\/p><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"copy_big wp-block-paragraph\">La tecnolog\u00eda de impresi\u00f3n 3D se origin\u00f3 en la d\u00e9cada de los 80 y, aunque en un inicio se usaba para generar prototipos r\u00e1pidos, esta tecnolog\u00eda de manufactura aditiva se ha desarrollado muy r\u00e1pido.&nbsp; Hoy en d\u00eda las compa\u00f1\u00edas se valen cada vez m\u00e1s de la impresi\u00f3n 3D para producir componentes para los usuarios finales. En un futuro cercano, ser\u00e1 incluso posible usar impresoras 3D para la fabricaci\u00f3n de productos conforme a las especificidades de los clientes a una escala industrial.<\/p>\n\n\n\n<p class=\"copy_big wp-block-paragraph\">Aparte de ofrecer beneficios exclusivos de manufactura, la impresi\u00f3n 3D es un proceso de producci\u00f3n sustentable pues minimiza los residuos. A diferencia de la manufactura sustractiva, la manufactura aditiva (impresi\u00f3n 3D) usa solo la cantidad necesaria de material. Asimismo, los residuos pl\u00e1sticos se pueden reciclar y usar para fabricar nuevos productos.<\/p>\n\n\n\n<p class=\"copy_big wp-block-paragraph\">Para aplicaciones que requieren propiedades similares al caucho, la industria de manufactura con frecuencia usa elast\u00f3meros termopl\u00e1sticos (TPE) para la impresi\u00f3n 3D. \u00daltimamente, los elast\u00f3meros termopl\u00e1sticos tambi\u00e9n se usan en la manufactura aditiva como una adici\u00f3n a los materiales principales de impresi\u00f3n (como PLA y ABS). Este tipo de elast\u00f3meros se puede usar para hacer productos de consumo, equipo deportivo y electr\u00f3nicos, as\u00ed como componentes para la industria automotriz y de construcci\u00f3n. Los TPE son recomendables para usarse como elast\u00f3meros de impresi\u00f3n 3D en el proceso de modelado de deposici\u00f3n fundida (FDM) de filamento, manufactura aditiva con pellets (PAM) y como polvo en el proceso de sinterizado selectivo por l\u00e1ser (SLS). El poliuretano termopl\u00e1stico (TPU) es una subcategor\u00eda del TPE. Como otros TPE, preferiblemente puede ser procesado en forma de filamento o granulado.<\/p>\n\n\n\n<p class=\"copy_big wp-block-paragraph\">Los TPE son ideales para aplicaciones que requieren flexibilidad, durabilidad y resistencia. La impresi\u00f3n 3D con TPE es menos costosa, en comparaci\u00f3n con otros materiales, por ejemplo, la impresi\u00f3n de silicona, y m\u00e1s adecuada para aplicaciones industriales a gran escala. Los TPE pueden ser usados tanto para prototipos como para la manufactura de componentes para usuarios finales. Los productos de Kuraray son particularmente adecuados para un mayor procesamiento de PLA, acrilonitrilo butadieno estireno (ABS) y policarbonato (PC).<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/3d-printing-thermoplastic-elastomers-additive-manufacturing.jpeg\" alt=\"\" class=\"wp-image-417\"\/><figcaption class=\"wp-element-caption\">En la manufactura aditiva, los elast\u00f3meros termopl\u00e1sticos se usan para soluciones avanzadas de impresi\u00f3n 3D.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-better-performance.jpg\" alt=\"\" class=\"wp-image-559\"\/><figcaption class=\"wp-element-caption\">Impresora Micro 3D en acci\u00f3n: Los elast\u00f3meros para impresi\u00f3n 3D fomentan la innovaci\u00f3n para un mejor rendimiento en la ingenier\u00eda mec\u00e1nica.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_yellow circle_right_top\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Tipos de impresi\u00f3n 3D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La impresi\u00f3n 3D hace referencia a varias tecnolog\u00edas de manufactura aditiva donde los objetos se construyen capa por capa. Existen diversos materiales que se usan en estos procesos, incluido el metal, la arena, el papel y, con mayor frecuencia, los pl\u00e1sticos. Los tres m\u00e9todos m\u00e1s comunes con relaci\u00f3n a los elast\u00f3meros para impresi\u00f3n 3D son impresi\u00f3n FDM\/PAM, SLA y SLS. La diferencia radica en el formato de los materiales alimentados a la m\u00e1quina (l\u00edquido, fundido o polvo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La impresi\u00f3n de filamento (FDM) y de pellet (PAM) son procesos de extrusi\u00f3n en los que los elast\u00f3meros para impresi\u00f3n 3D se funden para producir el producto final modelado. La impresi\u00f3n estereolitogr\u00e1fica (SLA) es un proceso de fotopolimerizaci\u00f3n en tanque, donde se deposita un l\u00edquido o una resina en capas para crear un objeto. El sinterizado selectivo por l\u00e1ser (impresi\u00f3n SLS) es una tecnolog\u00eda de fusi\u00f3n de capa de polvo donde se a\u00f1ade el polvo para producir un objeto.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-filament-printers.jpg\" alt=\"\" class=\"wp-image-551\"\/><figcaption class=\"wp-element-caption\">Capa por capa: las impresoras de filamento 3D producen prototipos funcionales y espec\u00edficos para los clientes.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"quality\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\" id=\"exterior\">\n<h2 class=\"wp-block-heading\">Gama de productos de Kuraray para impresi\u00f3n 3D<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La gama de productos de Kuraray incluye elast\u00f3meros termopl\u00e1sticos para la industria que cumplen las especificaciones de clientes para manufactura aditiva. Estos materiales generan resultados confiables, incluso en condiciones dif\u00edciles de producci\u00f3n. Los elast\u00f3meros para impresi\u00f3n 3D de Kuraray gozan de excelente elasticidad, propiedades de amortiguaci\u00f3n, transparencia y flujo, adem\u00e1s de elasticidad mejorada de resina. Ciertos materiales se pueden usar tambi\u00e9n como modificadores de pol\u00edmeros como el PLA. Las soluciones elastom\u00e9ricas para impresi\u00f3n 3D de Kuraray tienen ventajas y algunos retos respecto al proceso de impresi\u00f3n.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns col_benefits has-pale-cyan-blue-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_benefit.svg\" alt=\"\" class=\"wp-image-308\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Caracter\u00edsticas y beneficios<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Material suave y flexible<\/li>\n\n\n\n<li>Mejora la resistencia al impacto y el flujo de PLA, ABS y PC<\/li>\n\n\n\n<li>Alto grado de claridad<\/li>\n\n\n\n<li>Mayor vida \u00fatil<\/li>\n\n\n\n<li>Buena resistencia al impacto<\/li>\n\n\n\n<li>Flujo y eficiencia mejorados<\/li>\n\n\n\n<li>Propiedades de superficie suave al tacto<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_limitations.svg\" alt=\"\" class=\"wp-image-438\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Limitaciones<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a las propiedades f\u00edsicas, t\u00e9rmicas y mec\u00e1nicas de los elast\u00f3meros para impresi\u00f3n 3D, el proceso de manufactura aditiva sigue siendo un reto.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"quality\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\" id=\"exterior\">\n<h2 class=\"wp-block-heading\">Puntos a considerar al seleccionar la tecnolog\u00eda de impresi\u00f3n 3D m\u00e1s adecuada<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los criterios clave que deben considerarse al seleccionar la tecnolog\u00eda m\u00e1s adecuada para procesar elast\u00f3meros para impresi\u00f3n 3D son presupuesto, requerimientos mec\u00e1nicos, alimentaci\u00f3n del sistema, geometr\u00eda de las partes y apariencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La impresi\u00f3n 3D puede ser la soluci\u00f3n ideal para lotes peque\u00f1os, pero, por el contrario, otros procesos de manufactura pueden ser m\u00e1s adecuados para producciones a gran escala. Para componentes con geometr\u00edas complejas y funcionales, la impresi\u00f3n 3D es con frecuencia la \u00fanica opci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fin de seleccionar el proceso m\u00e1s adecuado, es necesario considerar los beneficios y limitaciones de varias tecnolog\u00edas a la luz de las especificaciones clave del producto. A continuaci\u00f3n, encontrar\u00e1 un resumen detallado de los procesos m\u00e1s comunes de impresi\u00f3n 3D para los elast\u00f3meros.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n\n\n\n<div class=\"circle_s bg_purple circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Impresi\u00f3n de filamentos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El modelado de deposici\u00f3n fundida (FDM) es una tecnolog\u00eda de impresi\u00f3n 3D de escritorio muy usada para producir partes pl\u00e1sticas. En este proceso de impresi\u00f3n de filamentos, los elast\u00f3meros para impresi\u00f3n 3D son extruidos y depositados, capa por capa, en la plataforma de construcci\u00f3n. El FDM es adecuado para modelado r\u00e1pido, no costoso y aplicaciones donde no se requiere un alto grado de precisi\u00f3n y calidad de superficie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El modelado por deposici\u00f3n fundida es el m\u00e9todo de impresi\u00f3n 3D m\u00e1s rentable para la manufactura de partes y prototipos termopl\u00e1sticos conforme a las especificaciones de los clientes. La gran disponibilidad de esta tecnolog\u00eda reduce los tiempos de ejecuci\u00f3n y entrega. Existe una amplia gama de materiales termopl\u00e1sticos para aplicaciones de modelado y funcionales no comerciales. Sin embargo, el FDM es menos adecuado para partes complejas, ya que la resoluci\u00f3n y la precisi\u00f3n son menores que en otras tecnolog\u00edas de manufactura de aditivos. Asimismo, los objetos producidos con esta tecnolog\u00eda pueden tener estructuras superficiales visibles y por lo tanto requerir procesamiento posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, entre m\u00e1s flexible sea la resina del elast\u00f3mero, m\u00e1s lenta y dif\u00edcil ser\u00e1 la alimentaci\u00f3n del proceso de impresi\u00f3n de filamentos.<\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/septon\/\" data-type=\"page\" data-id=\"43\">SEPTON\u2122<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-filament.jpg\" alt=\"\" class=\"wp-image-552\"\/><figcaption class=\"wp-element-caption\">Los elast\u00f3meros termopl\u00e1sticos pueden mejorar las caracter\u00edsticas y beneficios de un filamento para impresi\u00f3n 3D.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"copy_big strong wp-block-paragraph\"><strong>C\u00f3mo funciona el proceso de FDM:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se coloca un carrete de elast\u00f3meros para impresora 3D en la impresora. Este filamento de elast\u00f3mero se calienta en el cabezal de extrusi\u00f3n a la temperatura deseada, despu\u00e9s se alimenta al cabezal y la boquilla, donde se funde.<\/li>\n\n\n\n<li>El cabezal de extrusi\u00f3n se fija en un sistema de tres ejes. El material l\u00edquido es extruido a una hebra de filamento delgado que se deposita en capas predefinidas en una superficie, donde se enfr\u00edan y se solidifican. El enfriamiento se puede acelerar mediante un soplador en el cabezal de extrusi\u00f3n.<\/li>\n\n\n\n<li>Una vez que se completa una capa, se aplica la siguiente capa. El proceso se repite hasta que se complete la parte.<\/li>\n<\/ol>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-fdm-printer.svg\" alt=\"\" class=\"wp-image-550\"\/><figcaption class=\"wp-element-caption\">Representaci\u00f3n esquem\u00e1tica de una impresora FDM<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_beige circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-orange-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Impresi\u00f3n de pellets<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La diferencia entre la impresi\u00f3n de filamento y la impresi\u00f3n de pellets es el tipo de proceso de extrusi\u00f3n. En la impresi\u00f3n de filamentos, se alimenta un elast\u00f3mero base mediante un mecanismo. Esto aplica presi\u00f3n para presionar los elast\u00f3meros para impresi\u00f3n 3D mediante un bloque calentador, donde se mezcla para que pueda ser extruido mediante la boquilla. En los extrusores de pellets, los pellets se alimentan mediante una tolva a un cilindro con varias zonas de calentamiento. Un mecanismo de tornillo activado por un motor lleva los pellets a trav\u00e9s del cilindro a la boquilla extrusora.<\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/septon\/\" data-type=\"page\" data-id=\"43\">SEPTON\u2122<\/a><\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/septon-bio-series\/\" data-type=\"URL\" data-id=\"https:\/\/www.elastomer.kuraray.com\/products\/septon-bio-series\/\">SEPTON\u2122 BIO-series<\/a><\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/septon-q-series-insulated-cable-material\/\" data-type=\"page\" data-id=\"333\">SEPTON\u2122 Q-series<\/a><\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/hybrar\/\" data-type=\"page\" data-id=\"39\">HYBRAR\u2122<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/compounding-applications-plastic-industry-pellets.jpeg\" alt=\"\" class=\"wp-image-494\"\/><figcaption class=\"wp-element-caption\">Los pellets de elast\u00f3meros 3D resaltan la rentabilidad de los procesos de impresi\u00f3n de filamento.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns col_benefits has-luminous-vivid-orange-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_benefit.svg\" alt=\"\" class=\"wp-image-308\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Caracter\u00edsticas y beneficios<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mayor velocidad de producci\u00f3n\/deposici\u00f3n<\/li>\n\n\n\n<li>Mucho mayor opci\u00f3n de materiales, en especial materiales muy blandos<\/li>\n\n\n\n<li>Los pellets tienen un \u00edndice de rendimiento y precio mejorado en comparaci\u00f3n con los filamentos regulares<\/li>\n\n\n\n<li>Es posible producir partes m\u00e1s grandes<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<div class=\"circle_s bg_yellow circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Impresi\u00f3n SLA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La estereolitograf\u00eda (impresi\u00f3n SLA) es un proceso industrial com\u00fan para los elast\u00f3meros de impresi\u00f3n 3D. Sus principales caracter\u00edsticas son detalles precisos, superficies suaves, rangos reducidos de tolerancia y buenas propiedades mec\u00e1nicas, como resistencia a la intemperie, isotrop\u00eda y flexibilidad. Los objetos terminados tienen una estructura superficial de gran calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proceso es muy usado en el sector m\u00e9dico\/dental, por ejemplo, para producir modelos anat\u00f3micos. Tambi\u00e9n se usa para producir moldes para producci\u00f3n masiva, como juguetes y joyer\u00eda.<\/p>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/liquid-rubber\/\" data-type=\"URL\">KURARAY LIQUID RUBBER<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-sla-printing.jpg\" alt=\"\" class=\"wp-image-554\"\/><figcaption class=\"wp-element-caption\">La impresi\u00f3n SLA utiliza una estructura de soporte para hacer posibles objetos 3D de elast\u00f3meros detallados.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns col_benefits has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_benefit.svg\" alt=\"\" class=\"wp-image-308\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Caracter\u00edsticas y beneficios<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Producci\u00f3n de objetos de gran precisi\u00f3n con detalles complejos<\/li>\n\n\n\n<li>Superficie muy lisa (ideal para prototipos visuales)<\/li>\n\n\n\n<li>Existen materiales SLA especiales (por ejemplo, resinas claras, flexibles y para verter)<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_limitations.svg\" alt=\"\" class=\"wp-image-438\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Limitaciones<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los objetos por lo general son fr\u00e1giles, por lo que no son adecuados para prototipos de funcionamiento como otras t\u00e9cnicas de impresi\u00f3n 3D<\/li>\n\n\n\n<li>La apariencia y propiedades mec\u00e1nicas de los objetos se deterioran con el tiempo si se exponen a la luz solar<\/li>\n\n\n\n<li>Se requieren estructuras de soporte<\/li>\n\n\n\n<li>Se requiere procesamiento posterior<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-luminous-vivid-amber-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"copy_big strong wp-block-paragraph\"><strong>C\u00f3mo funciona la impresi\u00f3n SLA:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una impresora SLA com\u00fan de escritorio contiene un l\u00e1ser ultravioleta para curar cada capa del componente creado de un tanque, el cual contiene una resina sensible a la luz. Cuando el rayo l\u00e1ser UV toca la resina, el l\u00edquido se cura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con cada paso del l\u00e1ser se crea una capa muy delgada del objeto, la cual se adhiere a la capa anterior (o a la plataforma de construcci\u00f3n) y a la base del tanque. Despu\u00e9s la plataforma de construcci\u00f3n desciende en funci\u00f3n del grosor de la capa, hasta completar el proceso de producci\u00f3n.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-sla-printer.svg\" alt=\"\" class=\"wp-image-553\"\/><figcaption class=\"wp-element-caption\">Representaci\u00f3n esquem\u00e1tica de una impresora SLA<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"circle_b bg_cyan circle_left\"><\/div>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"quality\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\" id=\"exterior\">\n<h3 class=\"wp-block-heading\">Impresi\u00f3n SLS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En comparaci\u00f3n con la impresi\u00f3n SLA, el sinterizado selectivo por l\u00e1ser (impresi\u00f3n SLS) se encuentra todav\u00eda en desarrollo para superar sus limitaciones t\u00e9cnicas respecto a los elast\u00f3meros para impresi\u00f3n 3D. A\u00fan si la impresi\u00f3n SLS es una tecnolog\u00eda com\u00fan en la industria, los procedimientos de hoy en d\u00eda tienden a aglomerar los polvos base del TPE, pero en un futuro cercano, el procesamiento SLS, que cumple las normas de alta calidad de los fabricantes, tambi\u00e9n estar\u00e1 disponible para los elast\u00f3meros para impresi\u00f3n 3D.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns col_benefits has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_benefit.svg\" alt=\"\" class=\"wp-image-308\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Caracter\u00edsticas y beneficios<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Producci\u00f3n de partes funcionales y prototipos que requieren buenas propiedades mec\u00e1nicas<\/li>\n\n\n\n<li>El proceso de impresi\u00f3n no requiere estructura de soporte, lo cual permite a los fabricantes dise\u00f1ar objetos complejos<\/li>\n\n\n\n<li>Gran estabilidad mec\u00e1nica<\/li>\n\n\n\n<li>Gran proporci\u00f3n de precio y rendimiento, incluso para lotes peque\u00f1os y medianos<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full icon_benefit\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/04\/icon_limitations.svg\" alt=\"\" class=\"wp-image-438\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group tile_white tile_benefit has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#00b0e9\">Limitaciones<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La impresi\u00f3n SLS requiere procesamiento posterior y acabado debido a la superficie polvosa y la porosidad interna<\/li>\n\n\n\n<li>Dependiendo del tama\u00f1o y grosor de un objeto, el exceso de sinterizado puede causar la p\u00e9rdida de peque\u00f1os detalles o huecos<\/li>\n\n\n\n<li>Debido al proceso de sinterizado, es m\u00e1s probable que ocurra contracci\u00f3n y deformaci\u00f3n, dependiendo de la geometr\u00eda del objeto<\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"copy_big strong wp-block-paragraph\"><strong>C\u00f3mo funciona la impresi\u00f3n SLS:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un polvo se calienta por debajo del punto de fusi\u00f3n de los elast\u00f3meros para impresi\u00f3n 3D. El l\u00e1ser escanea una muestra del modelo 3D y calienta el polvo al punto de fusi\u00f3n del material, de tal forma que el polvo se funde junto con un objeto s\u00f3lido. Entonces la plataforma se mueve hacia abajo una capa a un contenedor o build chamber y la nueva capa se sinteriza de forma an\u00e1loga. Esto se repite hasta que se funde la \u00faltima capa. Hasta entonces, el polvo no fundido soporta el objeto impreso, por lo cual no se requiere una estructura adicional de soporte. Despu\u00e9s, el objeto se enfr\u00eda en la build chamber o contenedor.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-thermoplastic-elastomers-sls-printer.svg\" alt=\"\" class=\"wp-image-555\"\/><figcaption class=\"wp-element-caption\">Representaci\u00f3n esquem\u00e1tica de una impresora SLS<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-cyan-bluish-gray-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col_short is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading blue\">Impresi\u00f3n 3D &#8211; Oportunidades con la KURARAY LIQUID RUBBER<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Los grados curables por UV de KURARAY LIQUID RUBBER, UC-102M y UC-203M, pueden usarse para impresiones muy suaves o como modificadores de fotoresinas de acr\u00edlico o uretano para mejorar la resistencia al impacto de las partes acabadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos grados curables por UV tienen un excelente rendimiento, en especial:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Buenas propiedades a baja temperatura (Tg baja)<\/li>\n\n\n\n<li>Bajo \u00edndice de contracci\u00f3n<\/li>\n\n\n\n<li>Buena absorci\u00f3n de humedad y resistencia a la permeabilidad<\/li>\n\n\n\n<li>Suficientes propiedades de aislamiento<\/li>\n\n\n\n<li>Suficientes propiedades adhesivas<\/li>\n<\/ul>\n\n\n\n<p class=\"tag_link has-background wp-block-paragraph\" style=\"background-color:#d6d2c4\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/products\/liquid-rubber\/\" data-type=\"URL\">KURARAY LIQUID RUBBER<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.elastomer.kuraray.com\/es\/wp-content\/uploads\/sites\/5\/2024\/05\/3d-printing-techniques-overview-thermoplastic-elastomers.svg\" alt=\"\" class=\"wp-image-557\"\/><figcaption class=\"wp-element-caption\">Resumen de las t\u00e9cnicas de impresi\u00f3n 3D permitidas por los productos de Kuraray<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"contact\" class=\"wp-block-group holder_contact has-cyan-bluish-gray-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"heading_contact wp-block-paragraph\">Contacto<\/p>\n\n\n\n<form class=\"contact_form\" name=\"contact_form\" method=\"post\" onsubmit=\"return validateForm(this);\">\n<div class=\"form-group\">\n<label>Compa\u00f1\u00eda *<\/label> \n<input type=\"text\" class=\"form-control\" name=\"company\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>Pa\u00eds *<\/label> \n<select class=\"form-control\" name=\"country\" required=\"required\">\n<option value=\"\">Selecciona tu pa\u00eds&#8230;<\/option>\n<option value=\"Afghanistan\">Afghanistan<\/option>\n<option value=\"Aland Islands\">Aland Islands<\/option>\n<option value=\"Albania\">Albania<\/option>\n<option value=\"Algeria\">Algeria<\/option>\n<option value=\"American Samoa\">American Samoa<\/option>\n<option value=\"Andorra\">Andorra<\/option>\n<option value=\"Angola\">Angola<\/option>\n<option value=\"Anguilla\">Anguilla<\/option>\n<option value=\"Antigua and Barbuda\">Antigua and Barbuda<\/option>\n<option value=\"Argentina\">Argentina<\/option>\n<option value=\"Armenia\">Armenia<\/option>\n<option value=\"Aruba\">Aruba<\/option>\n<option value=\"Australia\">Australia<\/option>\n<option value=\"Austria\">Austria<\/option>\n<option value=\"Azerbaijan\">Azerbaijan<\/option>\n<option value=\"Bahamas\">Bahamas<\/option>\n<option value=\"Bahrain\">Bahrain<\/option>\n<option value=\"Bangladesh\">Bangladesh<\/option>\n<option value=\"Barbados\">Barbados<\/option>\n<option value=\"Belarus\">Belarus<\/option>\n<option value=\"Belgium\">Belgium<\/option>\n<option value=\"Belize\">Belize<\/option>\n<option value=\"Benin\">Benin<\/option>\n<option value=\"Bermuda\">Bermuda<\/option>\n<option value=\"Bhutan\">Bhutan<\/option>\n<option value=\"Bolivia\">Bolivia<\/option>\n<option value=\"Bonaire\">Bonaire<\/option>\n<option value=\"Bosnia and Herzegovina\">Bosnia and Herzegovina<\/option>\n<option value=\"Botswana\">Botswana<\/option>\n<option value=\"Bouvet Island\">Bouvet Island<\/option>\n<option value=\"Brazil\">Brazil<\/option>\n<option value=\"British Indian Ocean Territory\">British Indian Ocean Territory<\/option>\n<option value=\"Brunei Darussalam\">Brunei Darussalam<\/option>\n<option value=\"Bulgaria\">Bulgaria<\/option>\n<option value=\"Burkina Faso\">Burkina Faso<\/option>\n<option value=\"Burundi\">Burundi<\/option>\n<option value=\"Cambodia\">Cambodia<\/option>\n<option value=\"Cameroon\">Cameroon<\/option>\n<option value=\"Canada\">Canada<\/option>\n<option value=\"Cape Verde\">Cape Verde<\/option>\n<option value=\"Cayman Islands\">Cayman Islands<\/option>\n<option value=\"Central African Republic\">Central African Republic<\/option>\n<option value=\"Chad\">Chad<\/option>\n<option value=\"Chile\">Chile<\/option>\n<option value=\"China\">China<\/option>\n<option value=\"Christmas Island\">Christmas Island<\/option>\n<option value=\"Cocos (Keeling) Islands\">Cocos (Keeling) Islands<\/option>\n<option value=\"Colombia\">Colombia<\/option>\n<option value=\"Comoros\">Comoros<\/option>\n<option value=\"Congo\">Congo<\/option>\n<option value=\"Cook Islands\">Cook Islands<\/option>\n<option value=\"Costa Rica\">Costa Rica<\/option>\n<option value=\"Cote d'Ivoire\">Cote d&#8217;Ivoire<\/option>\n<option value=\"Croatia\">Croatia<\/option>\n<option value=\"Cuba\">Cuba<\/option>\n<option value=\"Curacao\">Curacao<\/option>\n<option value=\"Cyprus\">Cyprus<\/option>\n<option value=\"Czech Republic\">Czech Republic<\/option>\n<option value=\"Democratic Republic of the Congo\">Democratic Republic of the Congo<\/option>\n<option value=\"Denmark\">Denmark<\/option>\n<option value=\"Djibouti\">Djibouti<\/option>\n<option value=\"Dominica\">Dominica<\/option>\n<option value=\"Dominican Republic\">Dominican Republic<\/option>\n<option value=\"Ecuador\">Ecuador<\/option>\n<option value=\"Egypt\">Egypt<\/option>\n<option value=\"El Salvador\">El Salvador<\/option>\n<option value=\"Equatorial Guinea\">Equatorial Guinea<\/option>\n<option value=\"Eritrea\">Eritrea<\/option>\n<option value=\"Estonia\">Estonia <\/option>\n<option value=\"Eswatini\">Eswatini<\/option>\n<option value=\"Ethiopia\">Ethiopia<\/option>\n<option value=\"Falkland Islands (Malvinas)\">Falkland Islands (Malvinas)<\/option>\n<option value=\"Faroe Islands\">Faroe Islands<\/option>\n<option value=\"Fiji\">Fiji<\/option>\n<option value=\"Finland\">Finland<\/option>\n<option value=\"France\">France<\/option>\n<option value=\"French Guiana\">French Guiana<\/option>\n<option value=\"French Polynesia\">French Polynesia<\/option>\n<option value=\"French Southern Territories\">French Southern Territories<\/option>\n<option value=\"Gabon\">Gabon<\/option>\n<option value=\"Gambia\">Gambia<\/option>\n<option value=\"Georgia\">Georgia<\/option>\n<option value=\"Germany\">Germany<\/option>\n<option value=\"Ghana\">Ghana<\/option>\n<option value=\"Gibraltar\">Gibraltar<\/option>\n<option value=\"Greece\">Greece<\/option>\n<option value=\"Greenland\">Greenland<\/option>\n<option value=\"Grenada\">Grenada<\/option>\n<option value=\"Guadeloupe\">Guadeloupe<\/option>\n<option value=\"Guam\">Guam<\/option>\n<option value=\"Guatemala\">Guatemala<\/option>\n<option value=\"Guernsey\">Guernsey<\/option>\n<option value=\"Guinea\">Guinea<\/option>\n<option value=\"Guinea-Bissau\">Guinea-Bissau<\/option>\n<option value=\"Guyana\">Guyana<\/option>\n<option value=\"Haiti\">Haiti<\/option>\n<option value=\"Heard Island and McDonald Islands\">Heard Island and McDonald Islands<\/option>\n<option value=\"Holy See (Vatican City State)\">Holy See (Vatican City State)<\/option>\n<option value=\"Honduras\">Honduras<\/option>\n<option value=\"Hong Kong\">Hong Kong<\/option>\n<option value=\"Hungary\">Hungary<\/option>\n<option value=\"Iceland\">Iceland<\/option>\n<option value=\"India\">India<\/option>\n<option value=\"Indonesia\">Indonesia<\/option>\n<option value=\"Iran\">Iran<\/option>\n<option value=\"Iraq\">Iraq<\/option>\n<option value=\"Ireland\">Ireland<\/option>\n<option value=\"Isle of Man\">Isle of Man<\/option>\n<option value=\"Israel\">Israel<\/option>\n<option value=\"Italy\">Italy<\/option>\n<option value=\"Jamaica\">Jamaica<\/option>\n<option value=\"Japan\">Japan<\/option>\n<option value=\"Jersey\">Jersey<\/option>\n<option value=\"Jordan\">Jordan<\/option>\n<option value=\"Kazakhstan\">Kazakhstan<\/option>\n<option value=\"Kenya\">Kenya<\/option>\n<option value=\"Kiribati\">Kiribati<\/option>\n<option value=\"Korea, Democratic People's Republic of\">Korea, Democratic People&#8217;s Republic of<\/option>\n<option value=\"Korea, Republic of\">Korea(Republic of Korea)<\/option>\n<option value=\"Kosovo\">Kosovo<\/option>\n<option value=\"Kuwait\">Kuwait<\/option>\n<option value=\"Kyrgyzstan\">Kyrgyzstan<\/option>\n<option value=\"Lao People's Democratic Republic\">Lao People&#8217;s Democratic Republic<\/option>\n<option value=\"Latvia\">Latvia<\/option>\n<option value=\"Lebanon\">Lebanon<\/option>\n<option value=\"Lesotho\">Lesotho<\/option>\n<option value=\"Liberia\">Liberia<\/option>\n<option value=\"Libya\">Libya<\/option>\n<option value=\"Liechtenstein\">Liechtenstein<\/option>\n<option value=\"Lithuania\">Lithuania<\/option>\n<option value=\"Luxembourg\">Luxembourg<\/option>\n<option value=\"Macau\">Macau<\/option>\n<option value=\"Macedonia\">Macedonia<\/option>\n<option value=\"Madagascar\">Madagascar<\/option>\n<option value=\"Malawi\">Malawi<\/option>\n<option value=\"Malaysia\">Malaysia<\/option>\n<option value=\"Maldives\">Maldives<\/option>\n<option value=\"Mali\">Mali<\/option>\n<option value=\"Malta\">Malta<\/option>\n<option value=\"Marshall Islands\">Marshall Islands<\/option>\n<option value=\"Martinique\">Martinique<\/option>\n<option value=\"Mauritania\">Mauritania<\/option>\n<option value=\"Mauritius\">Mauritius<\/option>\n<option value=\"Mayotte\">Mayotte<\/option>\n<option value=\"Mexico\">Mexico<\/option>\n<option value=\"Micronesia\">Micronesia<\/option>\n<option value=\"Moldova\">Moldova<\/option>\n<option value=\"Monaco\">Monaco<\/option>\n<option value=\"Mongolia\">Mongolia<\/option>\n<option value=\"Montenegro\">Montenegro<\/option>\n<option value=\"Montserrat\">Montserrat<\/option>\n<option value=\"Morocco\">Morocco<\/option>\n<option value=\"Mozambique\">Mozambique<\/option>\n<option value=\"Myanmar\">Myanmar<\/option>\n<option value=\"Namibia\">Namibia<\/option>\n<option value=\"Nauru\">Nauru<\/option>\n<option value=\"Nepal\">Nepal<\/option>\n<option value=\"Netherlands\">Netherlands<\/option>\n<option value=\"New Caledonia\">New Caledonia<\/option>\n<option value=\"New Zealand\">New Zealand<\/option>\n<option value=\"Nicaragua\">Nicaragua<\/option>\n<option value=\"Niger\">Niger<\/option>\n<option value=\"Nigeria\">Nigeria<\/option>\n<option value=\"Niue\">Niue<\/option>\n<option value=\"Norfolk Island\">Norfolk Island<\/option>\n<option value=\"Northern Mariana Islands\">Northern Mariana Islands<\/option>\n<option value=\"Norway\">Norway<\/option>\n<option value=\"Oman\">Oman<\/option>\n<option value=\"Pakistan\">Pakistan<\/option>\n<option value=\"Palau\">Palau<\/option>\n<option value=\"Palestinian Territory\">Palestinian Territory<\/option>\n<option value=\"Panama\">Panama<\/option>\n<option value=\"Papua New Guinea\">Papua New Guinea<\/option>\n<option value=\"Paraguay\">Paraguay<\/option>\n<option value=\"Peru\">Peru<\/option>\n<option value=\"Philippines\">Philippines<\/option>\n<option value=\"Pitcairn\">Pitcairn<\/option>\n<option value=\"Poland\">Poland<\/option>\n<option value=\"Portugal\">Portugal<\/option>\n<option value=\"Puerto Rico\">Puerto Rico<\/option>\n<option value=\"Qatar\">Qatar<\/option>\n<option value=\"Reunion\">Reunion<\/option>\n<option value=\"Romania\">Romania<\/option>\n<option value=\"Russian Federation\">Russian Federation<\/option>\n<option value=\"Rwanda\">Rwanda<\/option>\n<option value=\"Saint Barthelemy\">Saint Barthelemy<\/option>\n<option value=\"Saint Helena\">Saint Helena<\/option>\n<option value=\"Saint Kitts and Nevis\">Saint Kitts and Nevis<\/option>\n<option value=\"Saint Lucia\">Saint Lucia<\/option>\n<option value=\"Saint Martin (French part)\">Saint Martin (French part)<\/option>\n<option value=\"Saint Pierre and Miquelon\">Saint Pierre and Miquelon<\/option>\n<option value=\"Saint Vincent and the Grenadines\">Saint Vincent and the Grenadines<\/option>\n<option value=\"Samoa\">Samoa<\/option>\n<option value=\"San Marino\">San Marino<\/option>\n<option value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option>\n<option value=\"Saudi Arabia\">Saudi Arabia<\/option>\n<option value=\"Senegal\">Senegal<\/option>\n<option value=\"Serbia\">Serbia<\/option>\n<option value=\"Seychelles\">Seychelles<\/option>\n<option value=\"Sierra Leone\">Sierra Leone<\/option>\n<option value=\"Singapore\">Singapore<\/option>\n<option value=\"Sint Maarten (Dutch part)\">Sint Maarten (Dutch part)<\/option>\n<option value=\"Slovakia\">Slovakia<\/option>\n<option value=\"Slovenia\">Slovenia<\/option>\n<option value=\"Solomon Islands\">Solomon Islands<\/option>\n<option value=\"Somalia\">Somalia<\/option>\n<option value=\"South Africa\">South Africa<\/option>\n<option value=\"South Georgia and the South Sandwich Isl\">South Georgia and the South Sandwich Isl<\/option>\n<option value=\"South Sudan\">South Sudan<\/option>\n<option value=\"Spain\">Spain<\/option>\n<option value=\"Sri Lanka\">Sri Lanka<\/option>\n<option value=\"Sudan\">Sudan<\/option>\n<option value=\"Suriname\">Suriname<\/option>\n<option value=\"Svalbard and Jan Mayen\">Svalbard and Jan Mayen<\/option>\n<option value=\"Sweden\">Sweden<\/option>\n<option value=\"Switzerland\">Switzerland<\/option>\n<option value=\"Syrian Arab Republic\">Syrian Arab Republic<\/option>\n<option value=\"Taiwan\">Taiwan<\/option>\n<option value=\"Tajikistan\">Tajikistan<\/option>\n<option value=\"Tanzania\">Tanzania<\/option>\n<option value=\"Thailand\">Thailand<\/option>\n<option value=\"Timor-Leste\">Timor-Leste<\/option>\n<option value=\"Togo\">Togo<\/option>\n<option value=\"Tokelau\">Tokelau<\/option>\n<option value=\"Tonga\">Tonga<\/option>\n<option value=\"Trinidad and Tobago\">Trinidad and Tobago<\/option>\n<option value=\"Tunisia\">Tunisia<\/option>\n<option value=\"Turkey\">Turkey<\/option>\n<option value=\"Turkmenistan\">Turkmenistan<\/option>\n<option value=\"Turks and Caicos Islands\">Turks and Caicos Islands<\/option>\n<option value=\"Tuvalu\">Tuvalu<\/option>\n<option value=\"Uganda\">Uganda<\/option>\n<option value=\"Ukraine\">Ukraine<\/option>\n<option value=\"United Arab Emirates\">United Arab Emirates<\/option>\n<option value=\"United Kingdom\">United Kingdom<\/option>\n<option value=\"United States\">United States<\/option>\n<option value=\"United States Minor Outlying Islands\">United States Minor Outlying Islands<\/option>\n<option value=\"Uruguay\">Uruguay<\/option>\n<option value=\"Uzbekistan\">Uzbekistan<\/option>\n<option value=\"Vanuatu\">Vanuatu<\/option>\n<option value=\"Venezuela\">Venezuela<\/option>\n<option value=\"Viet Nam\">Viet Nam<\/option>\n<option value=\"Virgin Islands, British\">Virgin Islands, British<\/option>\n<option value=\"Virgin Islands, U.S.\">Virgin Islands, U.S.<\/option>\n<option value=\"Wallis and Futuna\">Wallis and Futuna<\/option>\n<option value=\"Western Sahara\">Western Sahara<\/option>\n<option value=\"Yemen\">Yemen<\/option>\n<option value=\"Zambia\">Zambia<\/option>\n<option value=\"Zimbabwe\">Zimbabwe<\/option>\n<\/select>\n<\/div>\n\n<div class=\"form-group\">\n<label>Nombre *<\/label>\n<input type=\"text\" class=\"form-control\" name=\"first_name\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>Apellidos *<\/label>\n<input type=\"text\" class=\"form-control\" name=\"last_name\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label>Correo electr\u00f3nico *<\/label>\n<input type=\"email\" class=\"form-control\" name=\"email\" placeholder=\"\" required=\"required\">\n<\/div>\n\n<div class=\"form-group\">\n<label for=\"phone\">Numero telef\u00f3nico<\/label>\n<input type=\"tel\" class=\"form-control\" id=\"phone\" name=\"phone\"> \n<\/div>\n\n<div class=\"form-group\">\n<label>Mensaje *<\/label> \n<textarea class=\"form-control\" name=\"txt_Isp_Elas_Inquiry\" placeholder=\"\" required=\"required\"><\/textarea>\n<\/div>\n\n<div style=\"position:absolute; left:-9999px; top:-9999px\">\n<label for=\"pardot_extra_field\">Comments<\/label>\n<input type=\"text\" id=\"pardot_extra_field\" name=\"pardot_extra_field\">\n<\/div>\n  \n<div class=\"form-accepts\">\nConsulte el <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de privacidad del cliente<\/a> para conocer el manejo de informaci\u00f3n personal por parte del Grupo Kuraray relacionado con actividades de ventas y marketing.<br>\nSi acepta el <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de privacidad del cliente<\/a>, marque la casilla y env\u00ede su consulta.<br>\nConsulte la <a href=\"https:\/\/www.kuraray.com\/privacy\/\" target=\"blank\" rel=\"noopener\">Pol\u00edtica de privacidad<\/a> y la <a href=\"https:\/\/www.elastomer.kuraray.com\/cookie-policy\/\" target=\"blank\" rel=\"noopener\">Pol\u00edtica de cookies<\/a> para conocer el manejo de otra informaci\u00f3n personal.<br>\n<\/div>\n\n<div class=\"form-accepts\">\n<label class=\"switch\" for=\"checkbox\">\n     <input type=\"checkbox\" id=\"checkbox\" name=\"privacynotice\" value=\"true\" required=\"required\" oninvalid=\"this.setCustomValidity('Por favor, complete este campo.')\" onchange=\"this.setCustomValidity('')\">\n    <div class=\"slider round\"><\/div>\n  <\/label>\n <div class=\"switchlabel\"> Acepto el <a href=\"https:\/\/www.kuraray.com\/customer-privacy-notice\/\" target=\"blank\" rel=\"noopener\">Aviso de privacidad del cliente<\/a>. *<\/div>\n<\/div>\n  \n<div class=\"form-submit\">\n<div class=\"required footnote\">* Informaci\u00f3n necesaria<\/div>\n<input type=\"submit\" class=\"Submitbutton\" name=\"submit\" value=\"Enviar\">\n<\/div>\n<\/form>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los TPE de Kuraray son adecuados para la nueva tecnolog\u00eda de impresi\u00f3n 3D. Los elast\u00f3meros son soluciones para prototipos y partes de uso final con gran flexibilidad de dise\u00f1o.<br class=\"break-more-link\"><br class=\"break-more-link\"><a href=\"https:\/\/www.elastomer.kuraray.com\/es\/applications\/3d-printing\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":7,"featured_media":160,"parent":118,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-159","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/pages\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/comments?post=159"}],"version-history":[{"count":2,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/pages\/159\/revisions"}],"predecessor-version":[{"id":1489,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/pages\/159\/revisions\/1489"}],"up":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/pages\/118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/media\/160"}],"wp:attachment":[{"href":"https:\/\/www.elastomer.kuraray.com\/es\/wp-json\/wp\/v2\/media?parent=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}